{"id":1045,"date":"2010-05-30T14:54:23","date_gmt":"2010-05-30T12:54:23","guid":{"rendered":"http:\/\/www.tmcrew.org\/cm\/?p=1045"},"modified":"2010-05-30T14:58:41","modified_gmt":"2010-05-30T12:58:41","slug":"la-ciemmona-2010","status":"publish","type":"post","link":"https:\/\/www.tmcrew.org\/cm\/2010\/05\/la-ciemmona-2010\/","title":{"rendered":"la Ciemmona 2010"},"content":{"rendered":"<p><a href=\"http:\/\/picasaweb.google.it\/lh\/photo\/jjQAOyI6ns1XnxRJiHR4rw?feat=embedwebsite\"><img decoding=\"async\" src=\"http:\/\/lh4.ggpht.com\/_SEX53GZiRLk\/TAJcZ1hCnOI\/AAAAAAAANj4\/nsP8tq4F_-Q\/s400\/IMG_5078.JPG\" alt=\"\" \/><\/a><\/p>\n<p>Ancora una volta, anche quest&#8217;anno migliaia di persone che usualmente vanno in bici in citt\u00e0 o che almeno aspirano a poterlo fare in una citt\u00e0 meno inumana, si sono incontrate in sella ad una bici per dare vita alla settima Ciemmona, la Critical Mass nazionale, internazionale, intergalattica che si tiene ormai da sette anni a Roma.<\/p>\n<p>Nata come un bike pride e come un evento che ha dato il segno che<a href=\"http:\/\/www.tmcrew.org\/eco\/bike\/rinascimento.html\"> i tempi stanno cambiando<\/a> e che siamo in tanti\/e che non vogliamo essere pi\u00f9 complici delle guerre per il petrolio o dell&#8217;inquinamento delle compagnie petrolifere e che lo affermiamo tutti i giorni individualmente e una volta al mese collettivamente pedalando le bici nella realizzazione immediata e dal basso di un altro mondo possibile.<\/p>\n<p>La Ciemmona si conferma evento spontaneo, caotico, gioioso e incontrollabile e tutti quelli e quelle che spendono un minimo di energie nella partecipazione e nella realizzazione ne devono andare fieri\/e.<\/p>\n<p>In un mondo dove tutto \u00e8 merce, controllo, paura e gerarchia giornate come quella di ieri sono da incorniciare.<\/p>\n<p><a href=\"http:\/\/picasaweb.google.it\/lh\/photo\/ajYKorEas2Tu_7w9CO3eXw?feat=embedwebsite\"><img decoding=\"async\" src=\"http:\/\/lh4.ggpht.com\/_SEX53GZiRLk\/TAJf1OJh2LI\/AAAAAAAANkU\/5XWM2CQVVbc\/s400\/IMG_5175.JPG\" alt=\"\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ancora una volta, anche quest&#8217;anno migliaia di persone che usualmente vanno in bici in citt\u00e0 o che almeno aspirano a poterlo fare in una citt\u00e0 meno inumana, si sono incontrate in sella ad una bici per dare vita alla settima Ciemmona, la Critical Mass nazionale, internazionale, intergalattica che si tiene ormai da sette anni a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55,3],"tags":[],"class_list":["post-1045","post","type-post","status-publish","format-standard","hentry","category-ciemmona","category-cm-roma"],"_links":{"self":[{"href":"https:\/\/www.tmcrew.org\/cm\/wp-json\/wp\/v2\/posts\/1045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tmcrew.org\/cm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tmcrew.org\/cm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tmcrew.org\/cm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tmcrew.org\/cm\/wp-json\/wp\/v2\/comments?post=1045"}],"version-history":[{"count":2,"href":"https:\/\/www.tmcrew.org\/cm\/wp-json\/wp\/v2\/posts\/1045\/revisions"}],"predecessor-version":[{"id":1065,"href":"https:\/\/www.tmcrew.org\/cm\/wp-json\/wp\/v2\/posts\/1045\/revisions\/1065"}],"wp:attachment":[{"href":"https:\/\/www.tmcrew.org\/cm\/wp-json\/wp\/v2\/media?parent=1045"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tmcrew.org\/cm\/wp-json\/wp\/v2\/categories?post=1045"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tmcrew.org\/cm\/wp-json\/wp\/v2\/tags?post=1045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}