{"id":1135,"date":"2011-05-25T17:06:30","date_gmt":"2011-05-25T16:06:30","guid":{"rendered":"http:\/\/www.tmcrew.org\/cm\/?p=1135"},"modified":"2011-05-25T17:06:30","modified_gmt":"2011-05-25T16:06:30","slug":"la-ciemmona-2011-stiamo-arrivando","status":"publish","type":"post","link":"https:\/\/www.tmcrew.org\/cm\/2011\/05\/la-ciemmona-2011-stiamo-arrivando\/","title":{"rendered":"La Ciemmona 2011 ! Stiamo arrivando !"},"content":{"rendered":"<p><a href=\"http:\/\/www.ciemmona.org\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1136\" src=\"http:\/\/www.tmcrew.org\/cm\/wp-content\/ciemmona2011.bis_.jpg\" alt=\"\" width=\"420\" height=\"599\" srcset=\"https:\/\/www.tmcrew.org\/cm\/wp-content\/ciemmona2011.bis_.jpg 600w, https:\/\/www.tmcrew.org\/cm\/wp-content\/ciemmona2011.bis_-210x300.jpg 210w\" sizes=\"auto, (max-width: 420px) 100vw, 420px\" \/><\/a><\/p>\n<p>IL PROGRAMMA:<\/p>\n<p><strong>gioved\u00ec 26 maggio<\/strong><\/p>\n<p>aspettando LA CIEMMONA<br \/>\ndalle 20:30 stampa fai-da-te delle magliette ciemmoniche presso l&#8217;associazione <a href=\"http:\/\/www.exlavanderia.it\/\">Ex-Lavanderia<\/a><\/p>\n<p><strong>venerd\u00ec 27 maggio<\/strong><\/p>\n<p>COMPLEANNO CRITICAL MASS ROMA<br \/>\nh. 18,00 &#8211; partenza da Piazza del Colosseo +<br \/>\ncena (e concerto) post CM al Parco degli Acquedotti organizzata dal <a href=\"http:\/\/www.spartaco.it\/\">CSOA Spartaco<\/a><\/p>\n<p><strong>sabato 28 maggio<\/strong><\/p>\n<p>CIEMMONA 8<br \/>\nh. 14,30 &#8211; partenza dalle <a title=\"ciclofficine popolari di roma\" href=\"http:\/\/www.ciclofficinepopolari.it\/ciclofficine.html\">ciclofficine<\/a><br \/>\nh. 16,00 &#8211; partenza da Parco Schuster (giardini Basilica San Paolo)<br \/>\nh. 21,00 &#8211; cena + concerto di<a href=\"http:\/\/www.caponebungtbangt.com\/\" target=\"_blank\"> Capone &amp; Bungt Bangt <\/a>presso<br \/>\n<a href=\"http:\/\/www.exsnia.it\/\">CSOA ex-Snia Viscosa<\/a> &#8211; via Prenestina 173<\/p>\n<p><strong>domenica 29 maggio<\/strong><\/p>\n<p>ARRIVEDERCI ROMA!<br \/>\npicnic defaticante per salutare i nuovi e i vecchi amici (portatevi da mangiare, ma senza plastica!)<br \/>\nh. 12,00 &#8211; appuntamento al Parco di Traiano (Colle Oppio) e poi tutti a Villa Pamphili!<br \/>\nLaboratori improvvisati:<em> share your critical skills<\/em>!<\/p>\n<p>&#8212;&#8212;&#8212;<\/p>\n<p>Coloro i  quali vogliono stare a Roma durante l&#8217;evento e hanno bisogno di  ospitalit\u00e0 e di una bicicletta, a partire da gioved\u00ec 26 maggio sono i  benvenuti presso l&#8217;area campeggio allestita all&#8217;interno del <a href=\"http:\/\/www.exsnia.it\/\">CSOA exSnia  Viscosa<\/a>, a cura della Ciclofficina Popolare Don Chisciotte.<br \/>\nPer accedere al campeggio \u00e8 necessario prenotarsi tramite email  all&#8217;indirizzo accomodation@ciemmona.org indicando i giorni in cui avete  intenzione di stare e il numero di persone. se avete bisogno di  biciclette comunicatecelo! cercheremo di procurarvene il pi\u00f9 possibile  ma non escludiamo che molti saranno costretti a trovarle in altro modo o  chiederle in prestito.<br \/>\n<strong>IMPORTANTE: saranno accolte esclusivamente le richieste pervenute all&#8217;indirizzo accomodation@ciemmona.org<\/strong><\/p>\n<p>A PRESTO!<\/p>\n<p>DIFFONDETE L&#8217;INVITO IL PI\u00d9 CHE POTETE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>IL PROGRAMMA: gioved\u00ec 26 maggio aspettando LA CIEMMONA dalle 20:30 stampa fai-da-te delle magliette ciemmoniche presso l&#8217;associazione Ex-Lavanderia venerd\u00ec 27 maggio COMPLEANNO CRITICAL MASS ROMA h. 18,00 &#8211; partenza da Piazza del Colosseo + cena (e concerto) post CM al Parco degli Acquedotti organizzata dal CSOA Spartaco sabato 28 maggio CIEMMONA 8 h. 14,30 &#8211; [&hellip;]<\/p>\n","protected":false},"author":326,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1135","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/www.tmcrew.org\/cm\/wp-json\/wp\/v2\/posts\/1135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tmcrew.org\/cm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tmcrew.org\/cm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tmcrew.org\/cm\/wp-json\/wp\/v2\/users\/326"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tmcrew.org\/cm\/wp-json\/wp\/v2\/comments?post=1135"}],"version-history":[{"count":3,"href":"https:\/\/www.tmcrew.org\/cm\/wp-json\/wp\/v2\/posts\/1135\/revisions"}],"predecessor-version":[{"id":1139,"href":"https:\/\/www.tmcrew.org\/cm\/wp-json\/wp\/v2\/posts\/1135\/revisions\/1139"}],"wp:attachment":[{"href":"https:\/\/www.tmcrew.org\/cm\/wp-json\/wp\/v2\/media?parent=1135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tmcrew.org\/cm\/wp-json\/wp\/v2\/categories?post=1135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tmcrew.org\/cm\/wp-json\/wp\/v2\/tags?post=1135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}